{"id":299,"date":"2024-09-20T02:01:26","date_gmt":"2024-09-20T05:01:26","guid":{"rendered":"https:\/\/mendozaroadtrip.com\/?page_id=299"},"modified":"2026-04-27T16:57:56","modified_gmt":"2026-04-27T19:57:56","slug":"tours-bodegas","status":"publish","type":"page","link":"https:\/\/mendozaroadtrip.com\/pt\/tours-bodegas\/","title":{"rendered":"Tours Vin\u00edcolas"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbSection\u00bb module_class=\u00bbhome__portada\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/mendoza-road-tour-home-portada-background.jpg\u00bb height=\u00bb150vh\u00bb height_tablet=\u00bb140vh\u00bb height_phone=\u00bb120vh\u00bb height_last_edited=\u00bbon|phone\u00bb overflow-x=\u00bbhidden\u00bb overflow-y=\u00bbhidden\u00bb custom_padding=\u00bb20vh||0px||false|false\u00bb custom_padding_tablet=\u00bb20vh||0px||false|false\u00bb custom_padding_phone=\u00bb20vh||0px||false|false\u00bb custom_css_before=\u00bbcontent: \u00bb;||background-image: url(https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-portada-collage-1.png);||background-size: cover;||background-position: center 0%;||background-repeat: no-repeat;||position: absolute;||bottom: 0;||left: 0;||width: 100%;||height: 65%;||z-index: 3;\u00bb custom_css_after=\u00bbcontent: \u00bb;||background-image: url(https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-portada-collage-2.png);||background-size: cover;||background-position: center 0%;||background-repeat: no-repeat;||position: absolute;||bottom: -10vh;||left: 0;||width: 100%;||height: 100vh;||z-index: 4;\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb custom_css_before_last_edited=\u00bbon|phone\u00bb custom_css_before_phone=\u00bb    content: \u00bb;||    background-image: url(https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/10\/tour-bodegas-portada-new-1.png);||    background-size: cover;||    background-position: 25% 0%;||    background-repeat: no-repeat;||    position: absolute;||    bottom: 9vh;||    left: 0;||    width: 100%;||    height: 35vh;||    z-index: 3;\u00bb custom_css_before_tablet=\u00bbcontent: \u00bb;||background-image: url(https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-portada-collage-1.png);||background-size: cover;||background-position: center 0%;||background-repeat: no-repeat;||position: absolute;||bottom: -5%;||left: 0;||width: 100%;||height: 65%;||z-index: 3;\u00bb custom_css_after_last_edited=\u00bbon|phone\u00bb custom_css_after_phone=\u00bb    content: \u00bb;||    background-image: url(https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/10\/tour-bodegas-portada-new-2.png);||    background-size: cover;||    background-position: center 0%;||    background-repeat: no-repeat;||    position: absolute;||    bottom: 0vh;||    left: 0;||    width: 100%;||    height: 30vh;||    z-index: 4;\u00bb custom_css_after_tablet=\u00bbcontent: \u00bb;||background-image: url(https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-portada-collage-2.png);||background-size: cover;||background-position: center 0%;||background-repeat: no-repeat;||position: absolute;||bottom: -10vh;||left: 0;||width: 100%;||height: 100vh;||z-index: 4;\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb z_index=\u00bb5&#8243; width_tablet=\u00bb\u00bb width_phone=\u00bb85%\u00bb width_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbheight: 100%;||display: flex;||flex-direction: column;||justify-content: space-between;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_font_size=\u00bb50px\u00bb header_line_height=\u00bb60px\u00bb header_text_align_tablet=\u00bbleft\u00bb header_text_align_phone=\u00bbcenter\u00bb header_text_align_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb30px\u00bb header_font_size_last_edited=\u00bbon|tablet\u00bb header_line_height_tablet=\u00bb50px\u00bb header_line_height_phone=\u00bb36px\u00bb header_line_height_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1 class=\"translation-block\"><strong>Mendoza:<\/strong><br>Um passeio pela sua <span class=\"bigroads-font tituloH1\">adega<\/span><\/h1>\n<p>[\/et_pb_text][et_pb_icon font_icon=\u00bb&#x3b;||divi||400&#8243; icon_color=\u00bb#333333&#8243; icon_width=\u00bb46px\u00bb url=\u00bb#nosotros\u00bb align=\u00bbleft\u00bb align_tablet=\u00bbleft\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb animation_direction=\u00bbbottom\u00bb custom_css_main_element=\u00bbanimation: bounce2 2s ease infinite;\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbSection\u00bb module_class=\u00bbpopupSection\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb da_disable_devices=\u00bboff|off|off\u00bb disabled=\u00bbon\u00bb global_module=\u00bb888&#8243; global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2025\/12\/mendoza-road-trip-banner-diciembre-desktop.jpg\u00bb title_text=\u00bbmendoza-road-trip-banner-diciembre-desktop\u00bb url=\u00bbhttps:\/\/wa.link\/719p8t\u00bb url_new_window=\u00bbon\u00bb force_fullwidth=\u00bbon\u00bb disabled_on=\u00bbon|off|off\u00bb admin_label=\u00bbImagen\u00bb module_class=\u00bbbanner2025 popup__banner\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2025\/12\/mendoza-road-trip-banner-diciembre-mobile.jpg\u00bb title_text=\u00bbmendoza-road-trip-banner-diciembre-mobile\u00bb url=\u00bbhttps:\/\/wa.link\/719p8t\u00bb url_new_window=\u00bbon\u00bb force_fullwidth=\u00bbon\u00bb disabled_on=\u00bboff|on|on\u00bb module_class=\u00bbbanner2025 popup__banner\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbBanner Carnaval\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb da_disable_devices=\u00bboff|off|off\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2026\/01\/mrt-carnaval-banner-2026-desktop.jpg\u00bb title_text=\u00bbmrt-carnaval-banner-2026-desktop\u00bb url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6Ijg5OCJ9fQ==@\u00bb force_fullwidth=\u00bbon\u00bb disabled_on=\u00bbon|off|off\u00bb admin_label=\u00bbDesktop\u00bb module_class=\u00bbcarnavalBanner\u00bb _builder_version=\u00bb4.27.5&#8243; _dynamic_attributes=\u00bburl\u00bb _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2026\/01\/mrt-carnaval-banner-2026-mobile.jpg\u00bb title_text=\u00bbmrt-carnaval-banner-2026-mobile\u00bb url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6Ijg5OCJ9fQ==@\u00bb force_fullwidth=\u00bbon\u00bb disabled_on=\u00bboff|on|on\u00bb admin_label=\u00bbMobile\u00bb module_class=\u00bbcarnavalBanner\u00bb _builder_version=\u00bb4.27.5&#8243; _dynamic_attributes=\u00bburl\u00bb _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbBanner Mayo Fin\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb hover_enabled=\u00bb0&#8243; da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; module_class=\u00bbbannerSection finSemanaBanner\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2026\/04\/mrt-banner-fin-2026-desktop-1.jpg\u00bb title_text=\u00bbmrt-banner-fin-2026-desktop-1&#8243; url=\u00bbhttps:\/\/wa.link\/g33j1m\u00bb force_fullwidth=\u00bbon\u00bb disabled_on=\u00bbon|off|off\u00bb admin_label=\u00bbDesktop\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; url_new_window=\u00bbon\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2026\/04\/mrt-banner-mayo-fin-2026-desktop.jpg\u00bb title_text=\u00bbmrt-banner-mayo-fin-2026-desktop\u00bb url=\u00bbhttps:\/\/wa.link\/g33j1m\u00bb force_fullwidth=\u00bbon\u00bb disabled_on=\u00bboff|on|on\u00bb admin_label=\u00bbMobile\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; url_new_window=\u00bbon\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbSection\u00bb module_class=\u00bbhome__nosotros\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#DFDDD0&#8243; custom_padding=\u00bb100px||||false|false\u00bb custom_padding_tablet=\u00bb100px||80px||false|false\u00bb custom_padding_phone=\u00bb40px||||false|false\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb width_tablet=\u00bb90%\u00bb width_phone=\u00bb85%\u00bb width_last_edited=\u00bbon|phone\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-collage-principal.png\u00bb title_text=\u00bbtours-bodegas-collage-principal\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|tablet\u00bb module_class=\u00bbimgCollage collage3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb600px\u00bb max_width_tablet=\u00bb600px\u00bb max_width_phone=\u00bb90%\u00bb max_width_last_edited=\u00bbon|phone\u00bb module_alignment=\u00bbleft\u00bb custom_margin_tablet=\u00bb|0px|40px|0px|false|true\u00bb custom_margin_phone=\u00bb||40px||false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb50px||||false|false\u00bb custom_padding_tablet=\u00bb50px||||false|false\u00bb custom_padding_phone=\u00bb0px||||false|false\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb module_alignment_tablet=\u00bbleft\u00bb module_alignment_phone=\u00bbcenter\u00bb module_alignment_last_edited=\u00bbon|phone\u00bb custom_css_before=\u00bbcontent: \u00bb;||background-color: #D5B188;||width: 80%;||height: 80%;||position: absolute;||clip-path: polygon(50% 0%, 100% 50%, 50% 100%, 0% 50%);||top: 0;||right: 0;\u00bb global_colors_info=\u00bb{}\u00bb custom_css_before_last_edited=\u00bbon|phone\u00bb custom_css_before_phone=\u00bbcontent: \u00bb;||background-color: #D5B188;||width: 100%;||height: 100%;||position: absolute;||clip-path: polygon(50% 0%, 100% 50%, 50% 100%, 0% 50%);||top: 0;||right: 0;\u00bb custom_css_before_tablet=\u00bbcontent: \u00bb;||background-color: #D5B188;||width: 80%;||height: 80%;||position: absolute;||clip-path: polygon(50% 0%, 100% 50%, 50% 100%, 0% 50%);||top: 0;||right: 0;\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbtop\u00bb animation_duration=\u00bb1500ms\u00bb animation_intensity_slide=\u00bb10%\u00bb custom_css_main_element=\u00bbmargin: auto;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLora||||||||\u00bb text_text_color=\u00bb#333333&#8243; text_font_size=\u00bb22px\u00bb text_line_height=\u00bb24px\u00bb max_width_tablet=\u00bb560px\u00bb max_width_phone=\u00bb560px\u00bb max_width_last_edited=\u00bbon|tablet\u00bb custom_margin=\u00bb||80px||false|false\u00bb custom_margin_tablet=\u00bb||50px||false|false\u00bb custom_margin_phone=\u00bb||50px||false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb text_font_size_tablet=\u00bb22px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb text_line_height_tablet=\u00bb24px\u00bb text_line_height_phone=\u00bb22px\u00bb text_line_height_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bb\u00bb text_orientation_phone=\u00bbcenter\u00bb text_orientation_last_edited=\u00bbon|phone\u00bb module_alignment_tablet=\u00bbcenter\u00bb module_alignment_phone=\u00bbcenter\u00bb module_alignment_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p class=\"translation-block\"><span class=\"bigroads-font red\">Explore<\/span> as adegas <strong>emblem\u00e1ticas<\/strong> de Mendoza<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLora||||||||\u00bb text_text_color=\u00bb#78272E\u00bb text_font_size=\u00bb26px\u00bb text_line_height=\u00bb28px\u00bb background_color=\u00bb#F2DA08&#8243; text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb|auto||0px|false|false\u00bb custom_margin_tablet=\u00bb|auto||auto|false|false\u00bb custom_margin_phone=\u00bb|auto||auto|false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb15px|0px|15px|0px|true|true\u00bb custom_padding_tablet=\u00bb15px|60px|15px|60px|true|true\u00bb custom_padding_phone=\u00bb15px|50px|15px|50px|true|true\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb link_option_url=\u00bb#maipu-lujan\u00bb text_font_size_tablet=\u00bb22px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|tablet\u00bb text_line_height_tablet=\u00bb26px\u00bb text_line_height_phone=\u00bb22px\u00bb text_line_height_last_edited=\u00bbon|tablet\u00bb custom_css_main_element=\u00bbmax-width: 430px;\u00bb border_radii=\u00bbon|30px|30px|30px|30px\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb7.5px\u00bb box_shadow_color=\u00bb#bda502&#8243; global_colors_info=\u00bb{}\u00bb box_shadow_color__hover_enabled=\u00bbon|hover\u00bb box_shadow_color__hover=\u00bb#774c50&#8243; background__hover_enabled=\u00bbon|hover\u00bb background_color__hover=\u00bb#78272E\u00bb background_enable_color__hover=\u00bbon\u00bb text_text_color__hover_enabled=\u00bbon|hover\u00bb text_text_color__hover=\u00bb#FFFFFF\u00bb]<\/p>\n<p>Maip\u00fa | Luj\u00e1n de Cuyo<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLora||||||||\u00bb text_text_color=\u00bb#78272E\u00bb text_font_size=\u00bb26px\u00bb text_line_height=\u00bb28px\u00bb background_color=\u00bb#F2DA08&#8243; text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb|auto||0px|false|false\u00bb custom_margin_tablet=\u00bb|auto||auto|false|false\u00bb custom_margin_phone=\u00bb|auto||auto|false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb15px|80px|15px|80px|true|true\u00bb custom_padding_tablet=\u00bb15px|60px|15px|60px|true|true\u00bb custom_padding_phone=\u00bb15px|50px|15px|50px|true|true\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb link_option_url=\u00bb#valle-de-uco\u00bb text_font_size_tablet=\u00bb22px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|tablet\u00bb text_line_height_tablet=\u00bb26px\u00bb text_line_height_phone=\u00bb22px\u00bb text_line_height_last_edited=\u00bbon|tablet\u00bb custom_css_main_element=\u00bbmax-width: 430px;\u00bb border_radii=\u00bbon|30px|30px|30px|30px\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb7.5px\u00bb box_shadow_color=\u00bb#bda502&#8243; global_colors_info=\u00bb{}\u00bb box_shadow_color__hover_enabled=\u00bbon|hover\u00bb box_shadow_color__hover=\u00bb#774c50&#8243; background__hover_enabled=\u00bbon|hover\u00bb background_color__hover=\u00bb#78272E\u00bb background_enable_color__hover=\u00bbon\u00bb text_text_color__hover_enabled=\u00bbon|hover\u00bb text_text_color__hover=\u00bb#FFFFFF\u00bb]<\/p>\n<p>Vale de Uco<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbSection\u00bb module_id=\u00bbmaipu-lujan\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#78272E\u00bb custom_padding=\u00bb80px||80px||true|false\u00bb custom_padding_tablet=\u00bb80px||80px||true|false\u00bb custom_padding_phone=\u00bb40px||40px||false|false\u00bb da_popup_slug=\u00bbmaipu-lujan\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb width_tablet=\u00bb85%\u00bb width_phone=\u00bb85%\u00bb width_last_edited=\u00bbon|tablet\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code module_id=\u00bbcarousel\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb min_height=\u00bb30px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"galeria owl-carousel general\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <a class=\"fancybox\" rel=\"mygallery\" href=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-galeria-1.jpg\"><!-- [et_pb_line_break_holder] -->      <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-galeria-1.jpg\"><!-- [et_pb_line_break_holder] -->    <\/a><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <a class=\"fancybox\" rel=\"mygallery\" href=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-galeria-2.jpg\"><!-- [et_pb_line_break_holder] -->      <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-galeria-2.jpg\"><!-- [et_pb_line_break_holder] -->    <\/a><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <a class=\"fancybox\" rel=\"mygallery\" href=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-galeria-3.jpg\"><!-- [et_pb_line_break_holder] -->      <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-galeria-3.jpg\"><!-- [et_pb_line_break_holder] -->    <\/a><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->jQuery(document).ready(function($) {<!-- [et_pb_line_break_holder] -->    $('.galeria').owlCarousel({<!-- [et_pb_line_break_holder] -->        loop: true,<!-- [et_pb_line_break_holder] -->        margin: 10,<!-- [et_pb_line_break_holder] -->        nav: true, \/\/ Mostrar las flechas de navegaci\u00f3n<!-- [et_pb_line_break_holder] -->        dots: true, \/\/ Ocultar los puntos de paginaci\u00f3n<!-- [et_pb_line_break_holder] -->        responsive: {<!-- [et_pb_line_break_holder] -->            0: {<!-- [et_pb_line_break_holder] -->                items: 1 \/\/ 1 \u00edtem en mobile<!-- [et_pb_line_break_holder] -->            },<!-- [et_pb_line_break_holder] -->            600: {<!-- [et_pb_line_break_holder] -->                items: 1 \/\/ 2 \u00edtems en tablet<!-- [et_pb_line_break_holder] -->            },<!-- [et_pb_line_break_holder] -->            1000: {<!-- [et_pb_line_break_holder] -->                items: 1 \/\/ 3 \u00edtems en desktop<!-- [et_pb_line_break_holder] -->            }<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] -->    });<!-- [et_pb_line_break_holder] -->});<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><\/script>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text module_class=\u00bbtoursTitle\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLora||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb28px\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#FFFFFF\u00bb header_3_font_size=\u00bb36px\u00bb header_3_line_height=\u00bb42px\u00bb header_4_font=\u00bbLora|700|||||||\u00bb header_4_text_color=\u00bb#FFFFFF\u00bb header_4_font_size=\u00bb36px\u00bb header_4_line_height=\u00bb42px\u00bb custom_margin_tablet=\u00bb||30px||false|false\u00bb custom_margin_phone=\u00bb||30px||false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb0px|40px|||false|false\u00bb custom_padding_tablet=\u00bb10px|40px|||false|false\u00bb custom_padding_phone=\u00bb10px|20px|||false|false\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb22px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb text_line_height_tablet=\u00bb28px\u00bb text_line_height_phone=\u00bb24px\u00bb text_line_height_last_edited=\u00bbon|phone\u00bb header_3_font_size_tablet=\u00bb26px\u00bb header_3_font_size_phone=\u00bb26px\u00bb header_3_font_size_last_edited=\u00bbon|tablet\u00bb header_3_line_height_tablet=\u00bb32px\u00bb header_3_line_height_phone=\u00bb32px\u00bb header_3_line_height_last_edited=\u00bbon|tablet\u00bb header_4_font_size_tablet=\u00bb36px\u00bb header_4_font_size_phone=\u00bb28px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb header_4_line_height_tablet=\u00bb42px\u00bb header_4_line_height_phone=\u00bb32px\u00bb header_4_line_height_last_edited=\u00bbon|tablet\u00bb custom_css_main_element=\u00bbwidth: fit-content;\u00bb border_color_top=\u00bb#78272E\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>01<\/h4>\n<h3>DIA INTEIRO<\/h3>\n<p>Primera zona: Maip\u00fa | Luj\u00e1n de Cuyo<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLora||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb24px\u00bb max_width=\u00bb440px\u00bb max_width_tablet=\u00bb90%\u00bb max_width_phone=\u00bb100%\u00bb max_width_last_edited=\u00bbon|tablet\u00bb custom_margin=\u00bb||0px||false|false\u00bb text_font_size_tablet=\u00bb22px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb text_line_height_tablet=\u00bb26px\u00bb text_line_height_phone=\u00bb22px\u00bb text_line_height_last_edited=\u00bbon|phone\u00bb module_alignment_tablet=\u00bbleft\u00bb module_alignment_phone=\u00bbcenter\u00bb module_alignment_last_edited=\u00bbon|tablet\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Embarque num dia memor\u00e1vel com MENDOZA ROAD TRIP, percorrendo Maip\u00fa e Luj\u00e1n de Cuyo, as duas j\u00f3ias do vinho da primeira zona, onde nasceu a viticultura de Mendoza. Partindo da vibrante cidade de Mendoza, vamos lev\u00e1-lo a descobrir uma experi\u00eancia \u00fanica, onde a tradi\u00e7\u00e3o e a inova\u00e7\u00e3o se encontram em cada copo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbSection\u00bb module_class=\u00bbtourBodegas01&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#DFDDD0&#8243; z_index=\u00bb1&#8243; custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb40px||40px||true|false\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb1400px\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion open_toggle_text_color=\u00bb#78272E\u00bb open_toggle_background_color=\u00bbRGBA(255,255,255,0)\u00bb closed_toggle_background_color=\u00bbRGBA(255,255,255,0)\u00bb toggle_icon=\u00bb&#xf067;||fa||900&#8243; icon_color=\u00bb#78272E\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb toggle_text_color=\u00bb#78272E\u00bb toggle_font=\u00bb|800|||||||\u00bb toggle_font_size=\u00bb26px\u00bb toggle_line_height=\u00bb32px\u00bb closed_toggle_font=\u00bb|700|||||||\u00bb closed_toggle_font_size=\u00bb26px\u00bb closed_toggle_line_height=\u00bb32px\u00bb body_text_color=\u00bb#333333&#8243; body_font_size=\u00bb16px\u00bb body_line_height=\u00bb22px\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb toggle_font_size_tablet=\u00bb26px\u00bb toggle_font_size_phone=\u00bb22px\u00bb toggle_font_size_last_edited=\u00bbon|phone\u00bb toggle_line_height_tablet=\u00bb32px\u00bb toggle_line_height_phone=\u00bb26px\u00bb toggle_line_height_last_edited=\u00bbon|phone\u00bb closed_toggle_font_size_tablet=\u00bb26px\u00bb closed_toggle_font_size_phone=\u00bb22px\u00bb closed_toggle_font_size_last_edited=\u00bbon|phone\u00bb closed_toggle_line_height_tablet=\u00bb32px\u00bb closed_toggle_line_height_phone=\u00bb26px\u00bb closed_toggle_line_height_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb16px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb body_line_height_tablet=\u00bb22px\u00bb body_line_height_phone=\u00bb20px\u00bb body_line_height_last_edited=\u00bbon|phone\u00bb border_width_all=\u00bb0px\u00bb border_width_bottom=\u00bb4px\u00bb border_color_bottom=\u00bb#d5b288&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_accordion_item title=\u00bbOpci\u00f3n 1&#8243; open=\u00bbon\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"tourAcordeon__container\">\n<div class=\"acordeon__imgs\"><img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-01-opcion-1-antigal.jpg\" width=\"100%\" height=\"100%\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-01-opcion-1-decero.jpg\" width=\"100%\" height=\"100%\" \/><\/div>\n<div class=\"acordeon__texto\">\n<h4>1. Vin\u00edcola Antigal em Maip\u00fa<\/h4>\n<p>O nosso passeio come\u00e7a na hist\u00f3rica Bodega Antigal, onde o passado e o presente se combinam para criar vinhos excecionais. Descobrir\u00e1 a rica hist\u00f3ria da adega e o seu compromisso com a qualidade.<\/p>\n<\/div>\n<div class=\"acordeon__texto\">\n<h4>2. Finca Decero em Luj\u00e1n de Cuyo<\/h4>\n<p>Depois da experi\u00eancia na Bodega Antigal, seguimos para a elegante Finca Decero. Localizado num ambiente espetacular, oferecendo uma combina\u00e7\u00e3o perfeita entre natureza e sofistica\u00e7\u00e3o. Ser\u00e1 recebido com a calorosa hospitalidade da sua equipa e poder\u00e1 explorar as suas vinhas e as suas modernas instala\u00e7\u00f5es onde poder\u00e1 desfrutar de um almo\u00e7o gourmet.<\/p>\n<\/div>\n<div class=\"acordeon__boton reservar01\"><a href=\"https:\/\/wa.link\/dfxqay\" target=\"_blank\" rel=\"noopener\">Reservar <strong>Tour<\/strong><\/a><\/div>\n<\/div>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbOpci\u00f3n 2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<div class=\"tourAcordeon__container\">\n<div class=\"acordeon__imgs\"><img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-01-opcion-2-1.jpg\" width=\"100%\" height=\"100%\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-01-opcion-2-trapiche.jpg\" width=\"100%\" height=\"100%\" \/><\/div>\n<div class=\"acordeon__texto\">\n<h4>1. Vin\u00edcola Trapiche<\/h4>\n<p>Come\u00e7amos o passeio na ic\u00f3nica Bodega Trapiche, uma das adegas mais emblem\u00e1ticas da Argentina. Descobrir\u00e1 os processos de vinifica\u00e7\u00e3o que levaram o Trapiche a ser reconhecido internacionalmente.<\/p>\n<\/div>\n<div class=\"acordeon__texto\">\n<h4>2. Casa Vigil<\/h4>\n<p>O nosso passeio continua na Casa Vigil, o restaurante estrela do prestigiado en\u00f3logo Alejandro Vigil, galardoado com uma estrela Michelin. Aqui, os vinhos da sua autoria s\u00e3o perfeitamente complementados por uma proposta gastron\u00f3mica de primeira classe.<\/p>\n<\/div>\n<div class=\"acordeon__boton reservar02\"><a href=\"https:\/\/wa.link\/dfxqay\" target=\"_blank\" rel=\"noopener\">Reservar <strong>Tour<\/strong><\/a><\/div>\n<\/div>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbOpci\u00f3n 3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<div class=\"tourAcordeon__container\">\n<div class=\"acordeon__imgs\"><img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-01-opcion-3-alandes.jpg\" width=\"100%\" height=\"100%\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-01-opcion-3-domiciano.jpg\" width=\"100%\" height=\"100%\" \/><\/div>\n<div class=\"acordeon__texto\">\n<h4>1. Vin\u00edcola Alandes<\/h4>\n<p>Uma adega que celebra a diversidade e riqueza do terroir argentino. Explorar\u00e1 um projeto vitivin\u00edcola que se destaca pelo foco na cria\u00e7\u00e3o de vinhos que representem a ess\u00eancia de diferentes regi\u00f5es da Argentina.<\/p>\n<\/div>\n<div class=\"acordeon__texto\">\n<h4>2. Fam\u00edlia Domiciana<\/h4>\n<p>Ap\u00f3s a visita a Alandes, seguimos para a encantadora Bodega Familia Domiciano para desfrutar de um almo\u00e7o que celebra a tradi\u00e7\u00e3o e o amor pela terra. Permitir\u00e1 saborear o melhor da gastronomia mendoza num ambiente acolhedor e hospitaleiro.<\/p>\n<\/div>\n<div class=\"acordeon__boton reservar03\"><a href=\"https:\/\/wa.link\/dfxqay\" target=\"_blank\" rel=\"noopener\">Reservar <strong>Tour<\/strong><\/a><\/div>\n<\/div>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbOpci\u00f3n 4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<div class=\"tourAcordeon__container\">\n<div class=\"acordeon__imgs\"><img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-01-opcion-4-walter-bressia.jpg\" width=\"100%\" height=\"100%\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-01-opcion-4-susana-balbo.jpg\" width=\"100%\" height=\"100%\" \/><\/div>\n<div class=\"acordeon__texto\">\n<h4>1. Vin\u00edcola Walter Bressia<\/h4>\n<p>Come\u00e7amos a nossa aventura na Bodega Walter Bressia, uma adega familiar conhecida pela sua abordagem artesanal e pela produ\u00e7\u00e3o de vinhos exclusivos. Explorar\u00e1 esta adega boutique, onde a dedica\u00e7\u00e3o e o respeito pela viticultura se refletem em cada garrafa.<\/p>\n<\/div>\n<div class=\"acordeon__texto\">\n<h4>2. Adega Susana Balbo<\/h4>\n<p>Ap\u00f3s a visita a Walter Bressia, seguimos para a prestigiada Adega Susana Balbo, fundada pela primeira en\u00f3loga feminina da Argentina, Susana Balbo. Desfrutar\u00e1 de um almo\u00e7o que combina o melhor da gastronomia local com a inova\u00e7\u00e3o e criatividade que caracteriza esta garrafeira.<\/p>\n<\/div>\n<div class=\"acordeon__boton reservar04\"><a href=\"https:\/\/wa.link\/dfxqay\" target=\"_blank\" rel=\"noopener\">Reservar <strong>Tour<\/strong><\/a><\/div>\n<\/div>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb sticky_position=\u00bbtop\u00bb sticky_offset_top=\u00bb130px\u00bb sticky_limit_bottom=\u00bbrow\u00bb sticky_position_tablet=\u00bbtop\u00bb sticky_position_phone=\u00bbnone\u00bb sticky_position_last_edited=\u00bbon|phone\u00bb sticky_offset_top_tablet=\u00bb20px\u00bb sticky_offset_top_phone=\u00bb0px\u00bb sticky_offset_top_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#d5b288&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"tourItinerario__container\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<h3>Itiner\u00e1rio<\/h3>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-itinerario-svg-1.svg\" width=\"60px\" height=\"60px\"><!-- [et_pb_line_break_holder] -->    <pee><!-- [et_pb_line_break_holder] -->      Transfers privados de e para a cidade de Mendoza.<!-- [et_pb_line_break_holder] -->    <\/pee><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-itinerario-svg-2.svg\" width=\"60px\" height=\"60px\"><!-- [et_pb_line_break_holder] -->    <pee><!-- [et_pb_line_break_holder] -->      Visita guiada e degusta\u00e7\u00e3o na adega.<!-- [et_pb_line_break_holder] -->    <\/pee><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-itinerario-svg-4.svg\" width=\"60px\" height=\"60px\"><!-- [et_pb_line_break_holder] -->    <pee><!-- [et_pb_line_break_holder] -->      Almo\u00e7o gourmet e harmoniza\u00e7\u00e3o na segunda paragem.<!-- [et_pb_line_break_holder] -->    <\/pee><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-itinerario-svg-3.svg\" width=\"60px\" height=\"60px\"><!-- [et_pb_line_break_holder] -->    <pee><!-- [et_pb_line_break_holder] -->      Servi\u00e7o personalizado e atendimento exclusivo.<!-- [et_pb_line_break_holder] -->    <\/pee><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_text module_class=\u00bbcotiza01&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLora||||||||\u00bb text_text_color=\u00bb#78272E\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb background_color=\u00bb#F2DA08&#8243; text_orientation=\u00bbcenter\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb|auto||auto|false|false\u00bb custom_margin_tablet=\u00bb|auto||auto|false|false\u00bb custom_margin_phone=\u00bb|auto||auto|false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb15px|0px|15px|0px|true|true\u00bb custom_padding_tablet=\u00bb15px|60px|15px|60px|true|true\u00bb custom_padding_phone=\u00bb15px|50px|15px|50px|true|true\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb link_option_url=\u00bbhttps:\/\/wa.link\/8ovugt\u00bb link_option_url_new_window=\u00bbon\u00bb text_font_size_tablet=\u00bb22px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|tablet\u00bb text_line_height_tablet=\u00bb26px\u00bb text_line_height_phone=\u00bb22px\u00bb text_line_height_last_edited=\u00bbon|tablet\u00bb module_alignment_last_edited=\u00bboff|desktop\u00bb custom_css_main_element=\u00bbmax-width: 360px;\u00bb border_radii=\u00bbon|30px|30px|30px|30px\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb7.5px\u00bb box_shadow_color=\u00bb#bda502&#8243; global_colors_info=\u00bb{}\u00bb box_shadow_color__hover_enabled=\u00bbon|hover\u00bb box_shadow_color__hover=\u00bb#774c50&#8243; background__hover_enabled=\u00bbon|hover\u00bb background_color__hover=\u00bb#78272E\u00bb background_enable_color__hover=\u00bbon\u00bb text_text_color__hover_enabled=\u00bbon|hover\u00bb text_text_color__hover=\u00bb#FFFFFF\u00bb]<\/p>\n<p class=\"translation-block\">Refira a sua <strong>experi\u00eancia<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbSection\u00bb module_id=\u00bbvalle-de-uco\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#78272E\u00bb custom_padding=\u00bb80px||80px||true|false\u00bb custom_padding_tablet=\u00bb80px||80px||true|false\u00bb custom_padding_phone=\u00bb40px||40px||false|false\u00bb da_popup_slug=\u00bbvalle-de-uco\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb width_tablet=\u00bb85%\u00bb width_phone=\u00bb85%\u00bb width_last_edited=\u00bbon|tablet\u00bb max_width=\u00bb1400px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code module_id=\u00bbcarousel\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb min_height=\u00bb30px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"galeria owl-carousel general\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <a class=\"fancybox\" rel=\"mygallery\" href=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-galeria-1.jpg\"><!-- [et_pb_line_break_holder] -->      <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-galeria-1.jpg\"><!-- [et_pb_line_break_holder] -->    <\/a><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <a class=\"fancybox\" rel=\"mygallery\" href=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-galeria-2.jpg\"><!-- [et_pb_line_break_holder] -->      <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-galeria-2.jpg\"><!-- [et_pb_line_break_holder] -->    <\/a><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <a class=\"fancybox\" rel=\"mygallery\" href=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-galeria-3.jpg\"><!-- [et_pb_line_break_holder] -->      <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-galeria-3.jpg\"><!-- [et_pb_line_break_holder] -->    <\/a><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->jQuery(document).ready(function($) {<!-- [et_pb_line_break_holder] -->    $('.galeria').owlCarousel({<!-- [et_pb_line_break_holder] -->        loop: true,<!-- [et_pb_line_break_holder] -->        margin: 10,<!-- [et_pb_line_break_holder] -->        nav: true, \/\/ Mostrar las flechas de navegaci\u00f3n<!-- [et_pb_line_break_holder] -->        dots: true, \/\/ Ocultar los puntos de paginaci\u00f3n<!-- [et_pb_line_break_holder] -->        responsive: {<!-- [et_pb_line_break_holder] -->            0: {<!-- [et_pb_line_break_holder] -->                items: 1 \/\/ 1 \u00edtem en mobile<!-- [et_pb_line_break_holder] -->            },<!-- [et_pb_line_break_holder] -->            600: {<!-- [et_pb_line_break_holder] -->                items: 1 \/\/ 2 \u00edtems en tablet<!-- [et_pb_line_break_holder] -->            },<!-- [et_pb_line_break_holder] -->            1000: {<!-- [et_pb_line_break_holder] -->                items: 1 \/\/ 3 \u00edtems en desktop<!-- [et_pb_line_break_holder] -->            }<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] -->    });<!-- [et_pb_line_break_holder] -->});<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><\/script>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text module_class=\u00bbtoursTitle\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLora||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb28px\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_color=\u00bb#FFFFFF\u00bb header_3_font_size=\u00bb36px\u00bb header_3_line_height=\u00bb42px\u00bb header_4_font=\u00bbLora|700|||||||\u00bb header_4_text_color=\u00bb#FFFFFF\u00bb header_4_font_size=\u00bb36px\u00bb header_4_line_height=\u00bb42px\u00bb custom_margin_tablet=\u00bb||30px||false|false\u00bb custom_margin_phone=\u00bb||30px||false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb0px|40px|||false|false\u00bb custom_padding_tablet=\u00bb10px|40px|||false|false\u00bb custom_padding_phone=\u00bb10px|20px|||false|false\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb text_font_size_tablet=\u00bb22px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb text_line_height_tablet=\u00bb28px\u00bb text_line_height_phone=\u00bb24px\u00bb text_line_height_last_edited=\u00bbon|phone\u00bb header_3_font_size_tablet=\u00bb26px\u00bb header_3_font_size_phone=\u00bb26px\u00bb header_3_font_size_last_edited=\u00bbon|tablet\u00bb header_3_line_height_tablet=\u00bb32px\u00bb header_3_line_height_phone=\u00bb32px\u00bb header_3_line_height_last_edited=\u00bbon|tablet\u00bb header_4_font_size_tablet=\u00bb36px\u00bb header_4_font_size_phone=\u00bb28px\u00bb header_4_font_size_last_edited=\u00bbon|tablet\u00bb header_4_line_height_tablet=\u00bb42px\u00bb header_4_line_height_phone=\u00bb32px\u00bb header_4_line_height_last_edited=\u00bbon|tablet\u00bb custom_css_main_element=\u00bbwidth: fit-content;\u00bb border_color_top=\u00bb#78272E\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>02<\/h4>\n<h3>DIA INTEIRO<\/h3>\n<p>Vale de Uco<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLora||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb24px\u00bb max_width=\u00bb480px\u00bb max_width_tablet=\u00bb90%\u00bb max_width_phone=\u00bb100%\u00bb max_width_last_edited=\u00bbon|tablet\u00bb custom_margin=\u00bb||0px||false|false\u00bb text_font_size_tablet=\u00bb22px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb text_line_height_tablet=\u00bb26px\u00bb text_line_height_phone=\u00bb22px\u00bb text_line_height_last_edited=\u00bbon|phone\u00bb module_alignment_tablet=\u00bbleft\u00bb module_alignment_phone=\u00bbcenter\u00bb module_alignment_last_edited=\u00bbon|tablet\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Mergulhe na beleza do Vale do Uco com o MENDOZA ROAD TRIP. Este passeio leva-o a explorar uma das regi\u00f5es vin\u00edcolas mais impressionantes de Mendoza, onde as vinhas se encontram com a majestade dos Andes. Desfrute de um dia inteiro a descobrir adegas excecionais e paisagens de sonho no cora\u00e7\u00e3o do Vale de Uco.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbSection\u00bb module_class=\u00bbtourBodegas02&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#DFDDD0&#8243; z_index=\u00bb1&#8243; custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb40px||40px||true|false\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb1400px\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion open_toggle_text_color=\u00bb#78272E\u00bb open_toggle_background_color=\u00bbRGBA(255,255,255,0)\u00bb closed_toggle_background_color=\u00bbRGBA(255,255,255,0)\u00bb toggle_icon=\u00bb&#xf067;||fa||900&#8243; icon_color=\u00bb#78272E\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb toggle_text_color=\u00bb#78272E\u00bb toggle_font=\u00bb|800|||||||\u00bb toggle_font_size=\u00bb26px\u00bb toggle_line_height=\u00bb32px\u00bb closed_toggle_font=\u00bb|700|||||||\u00bb closed_toggle_font_size=\u00bb26px\u00bb closed_toggle_line_height=\u00bb32px\u00bb body_text_color=\u00bb#333333&#8243; body_font_size=\u00bb16px\u00bb body_line_height=\u00bb22px\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb toggle_font_size_tablet=\u00bb26px\u00bb toggle_font_size_phone=\u00bb22px\u00bb toggle_font_size_last_edited=\u00bbon|phone\u00bb toggle_line_height_tablet=\u00bb32px\u00bb toggle_line_height_phone=\u00bb26px\u00bb toggle_line_height_last_edited=\u00bbon|phone\u00bb closed_toggle_font_size_tablet=\u00bb26px\u00bb closed_toggle_font_size_phone=\u00bb22px\u00bb closed_toggle_font_size_last_edited=\u00bbon|phone\u00bb closed_toggle_line_height_tablet=\u00bb32px\u00bb closed_toggle_line_height_phone=\u00bb26px\u00bb closed_toggle_line_height_last_edited=\u00bbon|phone\u00bb body_font_size_tablet=\u00bb16px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb body_line_height_tablet=\u00bb22px\u00bb body_line_height_phone=\u00bb20px\u00bb body_line_height_last_edited=\u00bbon|phone\u00bb border_width_all=\u00bb0px\u00bb border_width_bottom=\u00bb4px\u00bb border_color_bottom=\u00bb#d5b288&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_accordion_item title=\u00bbOpci\u00f3n 1&#8243; open=\u00bbon\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"tourAcordeon__container\">\n<div class=\"acordeon__imgs\"><img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-opcion-1-domaine-bousquet.jpg\" width=\"100%\" height=\"100%\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-opcion-1-la-azul.jpg\" width=\"100%\" height=\"100%\" \/><\/div>\n<div class=\"acordeon__texto\">\n<h4>1. Adega Domaine Bousquet<\/h4>\n<p>Iniciamos a nossa viagem na conceituada Vin\u00edcola Domaine Bousquet, onde a fus\u00e3o da tradi\u00e7\u00e3o familiar francesa e do terroir argentino se manifesta em vinhos biol\u00f3gicos de excecional qualidade.<\/p>\n<\/div>\n<div class=\"acordeon__texto\">\n<h4>2. Vin\u00edcola La Azul<\/h4>\n<p>Depois de uma experi\u00eancia enriquecedora no Domaine Bousquet, seguimos para a encantadora Bodega La Azul. Com o seu ambiente familiar e acolhedor, o La Azul oferece uma experi\u00eancia aut\u00eantica e pessoal.<\/p>\n<\/div>\n<div class=\"acordeon__boton reservar01\"><a href=\"https:\/\/wa.link\/5wktqo\" target=\"_blank\" rel=\"noopener\">Reservar <strong>Tour<\/strong><\/a><\/div>\n<\/div>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbOpci\u00f3n 2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<div class=\"tourAcordeon__container\">\n<div class=\"acordeon__imgs\"><img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-opcion-2-salentein.jpg\" width=\"100%\" height=\"100%\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-opcion-2-andeluna.jpg\" width=\"100%\" height=\"100%\" \/><\/div>\n<div class=\"acordeon__texto\">\n<h4>1. Vin\u00edcola Salentein<\/h4>\n<p>Um \u00edcone da viticultura em Mendoza. Ser\u00e1 recebido com uma visita guiada que o levar\u00e1 atrav\u00e9s das suas impressionantes instala\u00e7\u00f5es, onde a arquitectura moderna se funde com a tradi\u00e7\u00e3o vitivin\u00edcola.<\/p>\n<\/div>\n<div class=\"acordeon__texto\">\n<h4>2. Vin\u00edcola Andeluna<\/h4>\n<p>Ap\u00f3s a enriquecedora visita a Salentein, seguimos para a encantadora Vin\u00edcola Andeluna, rodeada pelas belezas naturais da Cordilheira dos Andes. Oferece um cen\u00e1rio perfeito para uma experi\u00eancia culin\u00e1ria inesquec\u00edvel.<\/p>\n<\/div>\n<div class=\"acordeon__boton reservar02\"><a href=\"https:\/\/wa.link\/5wktqo\" target=\"_blank\" rel=\"noopener\">Reservar <strong>Tour<\/strong><\/a><\/div>\n<\/div>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbOpci\u00f3n 3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<div class=\"tourAcordeon__container\">\n<div class=\"acordeon__imgs\"><img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-opcion-3-alfa-crux.jpg\" width=\"100%\" height=\"100%\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-valle-de-uco-opcion-3-zuccardi.jpg\" width=\"100%\" height=\"100%\" \/><\/div>\n<div class=\"acordeon__texto\">\n<h4>1. Adega Alfa Crux<\/h4>\n<p>Iniciamos o nosso passeio na prestigiada Adega Alfa Crux, reconhecida pela sua abordagem inovadora e pelos vinhos de elevada qualidade. Explorar\u00e1 as suas vinhas aprendendo sobre o meticuloso processo de produ\u00e7\u00e3o que d\u00e1 vida aos seus vinhos excecionais.<\/p>\n<\/div>\n<div class=\"acordeon__texto\">\n<h4>2. Vale Zuccardi Uco<\/h4>\n<p>Ap\u00f3s a visita ao Alfa Crux, seguimos para a aclamada Zuccardi Valle de Uco, uma adega que representa inova\u00e7\u00e3o e tradi\u00e7\u00e3o no cora\u00e7\u00e3o do Vale de Uco. Reconhecida mundialmente e premiada como uma das melhores adegas do mundo, a Zuccardi oferece uma experi\u00eancia inigual\u00e1vel no seu restaurante PIeda Infinita, reconhecido pelo guia MIchelin.<\/p>\n<\/div>\n<div class=\"acordeon__boton reservar03\"><a href=\"https:\/\/wa.link\/5wktqo\" target=\"_blank\" rel=\"noopener\">Reservar <strong>Tour<\/strong><\/a><\/div>\n<\/div>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb sticky_position=\u00bbtop\u00bb sticky_offset_top=\u00bb130px\u00bb sticky_limit_bottom=\u00bbrow\u00bb sticky_position_tablet=\u00bbtop\u00bb sticky_position_phone=\u00bbnone\u00bb sticky_position_last_edited=\u00bbon|phone\u00bb sticky_offset_top_tablet=\u00bb20px\u00bb sticky_offset_top_phone=\u00bb0px\u00bb sticky_offset_top_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#d5b288&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"tourItinerario__container\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<h3>Itiner\u00e1rio<\/h3>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-itinerario-svg-1.svg\" width=\"60px\" height=\"60px\"><!-- [et_pb_line_break_holder] -->    <pee><!-- [et_pb_line_break_holder] -->      Transfers privados de e para a cidade de Mendoza.<!-- [et_pb_line_break_holder] -->    <\/pee><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-itinerario-svg-2.svg\" width=\"60px\" height=\"60px\"><!-- [et_pb_line_break_holder] -->    <pee><!-- [et_pb_line_break_holder] -->      Visita guiada e degusta\u00e7\u00e3o na adega.<!-- [et_pb_line_break_holder] -->    <\/pee><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-itinerario-svg-4.svg\" width=\"60px\" height=\"60px\"><!-- [et_pb_line_break_holder] -->    <pee><!-- [et_pb_line_break_holder] -->      Almo\u00e7o gourmet e harmoniza\u00e7\u00e3o na segunda paragem.<!-- [et_pb_line_break_holder] -->    <\/pee><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><!-- [et_pb_line_break_holder] -->    <img decoding=\"async\" src=\"https:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-itinerario-svg-3.svg\" width=\"60px\" height=\"60px\"><!-- [et_pb_line_break_holder] -->    <pee><!-- [et_pb_line_break_holder] -->      Servi\u00e7o personalizado e atendimento exclusivo.<!-- [et_pb_line_break_holder] -->    <\/pee><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_text module_class=\u00bbcotiza02&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLora||||||||\u00bb text_text_color=\u00bb#78272E\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb26px\u00bb background_color=\u00bb#F2DA08&#8243; text_orientation=\u00bbcenter\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb|auto||auto|false|false\u00bb custom_margin_tablet=\u00bb|auto||auto|false|false\u00bb custom_margin_phone=\u00bb|auto||auto|false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb15px|0px|15px|0px|true|true\u00bb custom_padding_tablet=\u00bb15px|60px|15px|60px|true|true\u00bb custom_padding_phone=\u00bb15px|50px|15px|50px|true|true\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb link_option_url=\u00bbhttps:\/\/wa.link\/r5pcca\u00bb link_option_url_new_window=\u00bbon\u00bb text_font_size_tablet=\u00bb22px\u00bb text_font_size_phone=\u00bb18px\u00bb text_font_size_last_edited=\u00bbon|tablet\u00bb text_line_height_tablet=\u00bb26px\u00bb text_line_height_phone=\u00bb22px\u00bb text_line_height_last_edited=\u00bbon|tablet\u00bb module_alignment_last_edited=\u00bboff|desktop\u00bb custom_css_main_element=\u00bbmax-width: 360px;\u00bb border_radii=\u00bbon|30px|30px|30px|30px\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb7.5px\u00bb box_shadow_color=\u00bb#bda502&#8243; global_colors_info=\u00bb{}\u00bb box_shadow_color__hover_enabled=\u00bbon|hover\u00bb box_shadow_color__hover=\u00bb#774c50&#8243; background__hover_enabled=\u00bbon|hover\u00bb background_color__hover=\u00bb#78272E\u00bb background_enable_color__hover=\u00bbon\u00bb text_text_color__hover_enabled=\u00bbon|hover\u00bb text_text_color__hover=\u00bb#FFFFFF\u00bb]<\/p>\n<p class=\"translation-block\">Refira a sua <strong>experi\u00eancia<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbSection\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/mendozaroadtrip.com\/wp-content\/uploads\/2024\/09\/tours-bodegas-experiencia-personalizada-background.jpg\u00bb parallax=\u00bbon\u00bb parallax_method=\u00bboff\u00bb custom_padding=\u00bb150px||150px||true|false\u00bb custom_padding_tablet=\u00bb150px||150px||true|false\u00bb custom_padding_phone=\u00bb60px||60px||true|false\u00bb da_disable_devices=\u00bboff|off|off\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|300|||||||\u00bb header_2_font=\u00bb|300|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb36px\u00bb header_2_line_height=\u00bb42px\u00bb header_2_font_size_tablet=\u00bb32px\u00bb header_2_font_size_phone=\u00bb24px\u00bb header_2_font_size_last_edited=\u00bbon|tablet\u00bb header_2_line_height_tablet=\u00bb36px\u00bb header_2_line_height_phone=\u00bb30px\u00bb header_2_line_height_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 class=\"translation-block\">Uma <strong>experi\u00eancia<\/strong> totalmente personaliz\u00e1vel<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>Mendoza:Un paseo por sus bodegasExplora las bodegas emblem\u00e1ticas de MendozaMaip\u00fa | Luj\u00e1n de CuyoValle de Uco01 FULL DAY Primera zona: Maip\u00fa | Luj\u00e1n de CuyoEmb\u00e1rcate en una jornada memorable con MENDOZA ROAD TRIP, recorriendo Maip\u00fa y Luj\u00e1n de Cuyo, las dos joyas vitivin\u00edcolas de la primera zona, donde naci\u00f3 la vitivinicultura mendocina. Partiendo desde la [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-299","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mendozaroadtrip.com\/pt\/wp-json\/wp\/v2\/pages\/299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mendozaroadtrip.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mendozaroadtrip.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mendozaroadtrip.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mendozaroadtrip.com\/pt\/wp-json\/wp\/v2\/comments?post=299"}],"version-history":[{"count":10,"href":"https:\/\/mendozaroadtrip.com\/pt\/wp-json\/wp\/v2\/pages\/299\/revisions"}],"predecessor-version":[{"id":1341,"href":"https:\/\/mendozaroadtrip.com\/pt\/wp-json\/wp\/v2\/pages\/299\/revisions\/1341"}],"wp:attachment":[{"href":"https:\/\/mendozaroadtrip.com\/pt\/wp-json\/wp\/v2\/media?parent=299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}